{"id":2208,"date":"2021-06-14T17:55:16","date_gmt":"2021-06-14T16:55:16","guid":{"rendered":"https:\/\/advancedseeds.com\/web\/?page_id=2208"},"modified":"2025-11-25T12:32:19","modified_gmt":"2025-11-25T11:32:19","slug":"condiciones-de-venta-y-contratacion","status":"publish","type":"page","link":"https:\/\/advancedseeds.com\/en\/condiciones-de-venta-y-contratacion\/","title":{"rendered":"Terms and Conditions of Sale and Contract"},"content":{"rendered":"\n<div class=\"row row-collapse\"  id=\"row-1574986385\">\n\n\n\t<div id=\"col-1579543090\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t<section class=\"section\" id=\"section_118919815\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"container section-title-container\" ><h1 class=\"section-title section-title-bold-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >Condiciones de Venta y Contrataci\u00f3n<\/span><b aria-hidden=\"true\"><\/b><\/h1><\/div>\n\n<p>Las presentes Condiciones regulan el uso de la tienda online <strong>www.advancedseeds.com<\/strong>, de la que es responsable legal <strong>Garden\u00a0Seeds Trading, S.L.<\/strong>, en adelante, \u201cAdvanced Seeds\u201d<strong>. <\/strong>Por medio de su aceptaci\u00f3n, el Usuario manifiesta que ha le\u00eddo, entiende y comprende lo aqu\u00ed expuesto y que asume todas sus obligaciones. Si el Usuario no estuviera de acuerdo con el contenido de este documento deber\u00e1 abandonar esta web, no pudiendo acceder ni disponer de los servicios que \u00e9sta ofrece. Igualmente, el Usuario acepta de forma expresa y sin excepciones que el acceso y la utilizaci\u00f3n del presente sitio web, de sus servicios y de los contenidos de dichos servicios tiene lugar bajo su \u00fanica y exclusiva responsabilidad.<\/p>\n<p>Estas Condiciones ser\u00e1n aceptadas por las partes sin reservas, y podr\u00e1n ser modificadas en cualquier momento y sin previo aviso, siendo responsabilidad del Usuario leerlas al realizar una compra o contrataci\u00f3n. Las condiciones vigentes en el momento de celebraci\u00f3n del contrato ser\u00e1n las que le resulten aplicables.<\/p>\n<h2>Normativa aplicable<\/h2>\n<p>El presente contrato electr\u00f3nico se celebra bajo la normativa espa\u00f1ola y en concreto bajo el r\u00e9gimen legal impuesto por la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico (LSSICE) y por la Ley 03\/2014, de 27 de marzo, General para la Defensa de los Consumidores y Usuarios (LGDCU).<\/p>\n<p>El contrato electr\u00f3nico no ser\u00e1 archivado por un tercero y el idioma para su conclusi\u00f3n es el espa\u00f1ol. Las presentes condiciones generales podr\u00e1n ser almacenadas y reproducidas en cualquier momento por el usuario que realice una compra mediante las opciones de su navegador de internet, y deben ser aceptadas antes de proceder al pago del pedido.<\/p>\n<h2>Cuenta de Usuario y Correcci\u00f3n de Errores<\/h2>\n<p>Para poder realizar compras online en esta tienda es necesario el registro mediante la creaci\u00f3n de una \u201cCuenta de Usuario\u201d. Podr\u00e1s registrarte en cualquier momento pinchando en el enlace correspondiente, o bien durante el proceso de compra. Una vez registrado, recibir\u00e1s un correo confirmando que el proceso se ha realizado con \u00e9xito y un recordatorio de los datos de acceso.<\/p>\n<p>Desde la cuenta se podr\u00e1n realizar compras, comprobar el historial de pedidos, cambiar la contrase\u00f1a, modificar los datos personales, modificar las direcciones de env\u00edo y facturaci\u00f3n, realizar comentarios, y otros tr\u00e1mites o gestiones relacionadas con tus compras.<\/p>\n<p>Adem\u00e1s, en cualquier momento, podr\u00e1s acceder a tu cuenta privada para comprobar la informaci\u00f3n personal y direcciones y, en caso de que fuera necesario, corregir los errores que puedan haber existido en la introducci\u00f3n de los datos o actualizar los mismos. Las direcciones de env\u00edo y facturaci\u00f3n tambi\u00e9n podr\u00e1n corregirse o actualizarse a lo largo del proceso de compra.<\/p>\n<p>Como Usuario, podr\u00e1s darte de baja en cualquier momento, enviando un correo electr\u00f3nico, desde la direcci\u00f3n que se quiere dar de baja, a la direcci\u00f3n info@advancedseeds.com, lo que conllevar\u00e1 la cancelaci\u00f3n de tus datos de car\u00e1cter personal.<\/p>\n<p>En cualquier caso, la creaci\u00f3n y cancelaci\u00f3n de una cuenta de usuario se regir\u00e1 por lo establecido en la Pol\u00edtica de Privacidad.<\/p>\n<h2>Proceso de Compra<\/h2>\n<p>Comprar en \u201cAdvanced Seeds\u201d es f\u00e1cil y sencillo, solo tienes que seguir los siguientes pasos:<\/p>\n<p><strong>1\u00ba.-<\/strong> Seleccionar los productos que desees adquirir de entre los ofrecidos por \u201cAdvanced Seeds\u201d. Clicando en cada producto, se accede a su ficha, que incluye descripci\u00f3n detallada con la informaci\u00f3n, caracter\u00edsticas principales y precio. Si necesitas m\u00e1s informaci\u00f3n, no dudes en preguntarnos. NOTA: En el caso de fichas de producto con fotograf\u00eda, los productos pueden sufrir ligeras variaciones de color o textura con respecto a la fotograf\u00eda que aparece en la web, debido a diferentes factores, por ejemplo, a la resoluci\u00f3n de su monitor. No obstante, haremos lo posible para que las im\u00e1genes sean lo m\u00e1s fieles posibles a la realidad.<\/p>\n<p><strong>2\u00ba.-<\/strong> Una vez seleccionado el\/los producto\/s que desees comprar, deber\u00e1s pulsar el bot\u00f3n \u201cA\u00f1adir al carrito\u201d, quedando incorporado el producto a tu carrito de la compra. Si lo deseas, podr\u00e1s seguir a\u00f1adiendo m\u00e1s productos al carrito, o proceder directamente al pago.<\/p>\n<p><strong>3\u00ba.-<\/strong> Concluida la selecci\u00f3n de productos, aparecer\u00e1 un resumen identificando el\/los art\u00edculo\/s seleccionado\/s. Finalmente, para continuar con tu pedido, deber\u00e1s pulsar el bot\u00f3n \u201cFinalizar compra\u201d.<\/p>\n<p><strong>4\u00ba.-<\/strong> Como hemos indicado en apartados anteriores, al finalizar tu compra, deber\u00e1s registrarte, indicando tus datos de contacto y direcci\u00f3n. En tus pr\u00f3ximas compras no tendr\u00e1s que introducir de nuevo tus datos, pues quedar\u00e1n almacenados en tu Cuenta de Usuario.<\/p>\n<p><strong>5\u00ba.-<\/strong> Por \u00faltimo, deber\u00e1s aceptar las presentes Condiciones de Venta y elegir el medio de pago entre los ofrecidos por \u201cAdvanced Seeds\u201d (ver apartado siguiente).<\/p>\n<p><strong>6\u00ba.-<\/strong> Una vez finalizado el proceso de compra, te enviaremos un correo electr\u00f3nico en el que se detallar\u00e1n los datos de la misma, as\u00ed como justificante de compra o factura en formato digital. Si no recibes este correo en 24 horas, o si aprecias cualquier error en los datos introducidos, ponte en contacto con nosotros por cualquiera de los siguientes medios:<\/p>\n<ul>\n<li>Llamando al 968 629 309<\/li>\n<li>Notific\u00e1ndolo en la secci\u00f3n de contacto de esta web<\/li>\n<li>Escribiendo a la direcci\u00f3n de correo info@advancedseeds.com<\/li>\n<\/ul>\n<p>De igual forma, si deseas que te enviemos la factura en papel, ponte en contacto con nosotros y te la haremos llegar sin ning\u00fan tipo de coste adicional.<\/p>\n<h2>Formas de pago<\/h2>\n<p>\u201cAdvanced Seeds\u201d dispone de diversas modalidades de pago:<\/p>\n<ul>\n<li>Tarjeta de cr\u00e9dito o d\u00e9bito<\/li>\n<li>PayPal<\/li>\n<\/ul>\n<p>A continuaci\u00f3n, especificamos las condiciones para cada una de estas formas de pago.<\/p>\n<p><strong><em>Tarjeta de cr\u00e9dito o d\u00e9bito<\/em><\/strong><\/p>\n<p>El pago mediante tarjeta de cr\u00e9dito o d\u00e9bito se realiza a trav\u00e9s de la pasarela de pago seguro de Sabadell. Mediante esta modalidad de pago, \u201cAdvanced Seeds\u201d nunca recoge ni manipula ning\u00fan dato del cliente relativo a su n\u00famero de tarjeta. Todos los datos son tratados directamente por Sabadell, de forma que \u201cAdvanced Seeds\u201d siempre pueda ofrecer la mayor seguridad, transparencia y confidencialidad en la transacci\u00f3n.<\/p>\n<p><strong><em>Paypal<\/em><\/strong><\/p>\n<p>Realiza el pago con tu cuenta de PayPal. Mediante esta modalidad de pago, \u201cAdvanced Seeds\u201d nunca recoge ni manipula ning\u00fan dato bancario. Todos los datos son tratados directamente por Paypal, de forma que \u201cAdvanced Seeds\u201d siempre pueda ofrecer la mayor transparencia, seguridad y confidencialidad en la transacci\u00f3n.<\/p>\n<h2>Condiciones de env\u00edo<\/h2>\n<p>Se realizar\u00e1n env\u00edos a:<\/p>\n<ul>\n<li>Espa\u00f1a Peninsular<\/li>\n<li>Islas Baleares<\/li>\n<li>Islas Canarias<\/li>\n<li>Ceuta y Melilla<\/li>\n<li>Internacional.<\/li>\n<\/ul>\n<p>El env\u00edo se har\u00e1 por la empresa de mensajer\u00eda urgente <strong>Nacex y Correos<\/strong>.<\/p>\n<p><strong>El porte ser\u00e1 gratuito en pedidos superiores a 25\u20ac en Pen\u00ednsula e Islas, 50\u20ac en Europa, y superiores a 100\u20ac en Australia, Asia, \u00c1frica y Am\u00e9rica. <\/strong>En el resto de los casos, el precio del porte ser\u00e1 de:<\/p>\n<ul>\n<li>Pen\u00ednsula: 5,90\u20ac<\/li>\n<li>Europa: 9,50\u20ac<\/li>\n<li>Australia: 45\u20ac<\/li>\n<li>Asia: 55\u20ac<\/li>\n<li>\u00c1frica: 19,50\u20ac<\/li>\n<li>Am\u00e9rica: 19,50\u20ac<\/li>\n<\/ul>\n<p>La empresa de mensajer\u00eda entrega habitualmente en horario comercial, as\u00ed que, si tienes alguna preferencia de horario para la entrega, puedes indic\u00e1rnosla en el comentario del pedido y se tratar\u00e1 de cumplir (en la medida de las posibilidades de ruta y horario de la empresa de transportes).<\/p>\n<h2>Plazos de entrega<\/h2>\n<p>El plazo de entrega se muestra durante el proceso de compra, y supone la aceptaci\u00f3n del mismo por tu parte.<\/p>\n<p>En caso de incumplimiento de plazos de entrega, deber\u00e1s indicarnos un plazo adicional adecuado a las circunstancias que provocaron el retraso inicial. En caso de que tampoco podamos entregar el bien en dicho plazo adicional, podr\u00e1s resolver el contrato. En caso de que el plazo de entrega sea esencial a la vista de todas las circunstancias que concurran en la celebraci\u00f3n del contrato o cuando nos hayas informado, antes de la compra, de que es esencial la entrega antes de una fecha determinada o en una fecha determinada. En tales casos, podr\u00e1s resolver el contrato de inmediato.<\/p>\n<p>En cualquier caso, de producirse la resoluci\u00f3n del contrato, se reembolsar\u00e1n las cantidades abonadas en su totalidad.<\/p>\n<p>En el caso de que el Usuario compre alg\u00fan producto que a\u00fan no ha salido a la venta, pero que ya tiene fecha de lanzamiento, los plazos de env\u00edo ser\u00e1n provisionales y modificables, y estar\u00e1n sujetos al n\u00famero de unidades por producto que los proveedores dispongan en cada momento. En tal caso, nos pondremos en contacto contigo para informarte de las variaciones sufridas en dichos productos, as\u00ed como de la posibilidad de rescindir el contrato.<\/p>\n<p>En algunos casos podr\u00eda producirse una falta de existencias. Nuestro personal se pondr\u00e1 en contacto contigo para darte una soluci\u00f3n y para informarte del plazo de entrega una vez est\u00e9 disponible el producto seleccionado, o para rescindir el contrato si as\u00ed lo deseas.<\/p>\n<p>IMPORTANTE: En general, no nos hacemos responsables del incumplimiento o retraso de obligaciones que se deban a causas fuera de nuestro control, como en caso de fuerza mayor (confinamiento por estado de alarma, por ejemplo), cat\u00e1strofes naturales, huelgas, accidentes, etc. De surgir alguna incidencia, nos pondremos en contacto contigo para solucionar la incidencia.<\/p>\n<h2>Precios, impuestos, tasas y aranceles<\/h2>\n<p>Los precios est\u00e1n expresados en Euros. Los precios de los productos de \u201cAdvanced Seeds\u201d pueden variar, pero los posibles cambios no afectar\u00e1n a los pedidos con respecto a los que ya haya sido enviada una Confirmaci\u00f3n de Env\u00edo.<\/p>\n<p>El precio final de los productos adquiridos podr\u00eda variar seg\u00fan los impuestos aplicables en cada caso, o en funci\u00f3n de la direcci\u00f3n de env\u00edo y perfil del comprador (particular o profesional). A efectos informativos, salvo en aquellas actividades no sujetas o exentas de IVA, ser\u00e1n de aplicaci\u00f3n los siguientes impuestos en los art\u00edculos de nuestra web:<\/p>\n<ul>\n<li>El PVP de los art\u00edculos con direcci\u00f3n de env\u00edo a la Pen\u00ednsula y Baleares incluye IVA en cualquier caso.<\/li>\n<li>El PVP de los art\u00edculos con direcci\u00f3n de env\u00edo a otros pa\u00edses de la UE, y siendo el comprador una persona f\u00edsica (particular) incluye IVA.<\/li>\n<li>El PVP de los art\u00edculos con direcci\u00f3n de env\u00edo a otros pa\u00edses de la UE, y siendo el comprador una empresa o profesional, NO incluye IVA siempre que est\u00e9 dado de alta en el Registro de Operadores Intracomunitario (en cuyo caso nos tendr\u00e1n que facilitar el C\u00f3digo de Identificaci\u00f3n Fiscal v\u00e1lido). En caso de no estar dado de alta como O.I., el PVP incluye IVA.<\/li>\n<li>El PVP de los art\u00edculos con direcci\u00f3n de env\u00edo a Islas Canarias o Ceuta y Melilla y, en general, cualquier pa\u00eds que no sea de la UE, NO incluye IVA, ya que la operaci\u00f3n se trata como una exportaci\u00f3n. El precio indicado en cada art\u00edculo es el precio final del mismo para los env\u00edos a estos destinos. \u201cAdvanced Seeds\u201d no se har\u00e1 cargo de la DUA ni de los gastos de importaci\u00f3n e impuestos (ISPI, IGIC), tasas o aranceles que se generen en la aduana de destino, de ser el caso.<\/li>\n<\/ul>\n<h2>Baja de cuentas y servicio, cancelaci\u00f3n y bloqueo<\/h2>\n<p>Las cuentas de Usuario no se eliminan por falta de uso. El Usuario pueden darse de baja solicitando la misma al personal de \u201cAdvanced Seeds\u201d, enviando un email a info@advancedseeds.com o a trav\u00e9s del perfil de su cuenta.<\/p>\n<p>En caso de impago de un pedido, \u00e9sta podr\u00e1 ser suspendido temporalmente hasta la que situaci\u00f3n de impago se haya resuelto por parte del Usuario. En caso de transcurrir m\u00e1s de 15 d\u00edas, \u201cAdvanced Seeds\u201d podr\u00e1 proceder a la cancelaci\u00f3n del pedido.<\/p>\n<p>\u201cAdvanced Seeds\u201d se reserva el derecho de bloquear sin previo aviso el acceso a la cuenta de Usuario (o eliminar directamente la cuenta de Usuario), si la usa de un modo ilegal o incumple las obligaciones y normas aqu\u00ed establecidas, hecho que ser\u00e1 comunicado mediante correo electr\u00f3nico. El bloqueo o eliminaci\u00f3n de la cuenta de Usuario no tendr\u00e1 efecto alguno sobre la obligaci\u00f3n de pagar por los productos adquiridos, si fuera el caso.<\/p>\n<p>En casos excepcionales, bajo el libre criterio de los administradores de \u201cAdvanced Seeds\u201d, y evaluando la gravedad del hecho, los administradores podr\u00e1n optar por apercibir al Usuario infractor, antes de eliminar o bloquear su cuenta definitivamente.<\/p>\n<p>Al registrarse como Usuario, est\u00e1 de acuerdo en que los titulares de este sitio se reservan el derecho, pudiendo actuar en cualquier momento y sin previo aviso, de modificar o discontinuar este sitio web y sus servicios, o de eliminar datos provistos, ya sea de manera temporal o permanente.<\/p>\n<h2>Devoluciones<\/h2>\n<p>En \u201cAdvanced Seeds\u201d deseamos la satisfacci\u00f3n con tu pedido. Por ello, te facilitamos varios m\u00e9todos para efectuar la devoluci\u00f3n de un art\u00edculo que pudiera no ajustarse a tus necesidades o expectativas. Posibles casos de devoluci\u00f3n o desistimiento:<\/p>\n<ol>\n<li><strong><u> El producto es err\u00f3neo, tiene un defecto o ha sido da\u00f1ado durante el transporte: <\/u><\/strong><\/li>\n<\/ol>\n<p>Prestamos mucha atenci\u00f3n a que todos nuestros env\u00edos se realicen de manera correcta. S\u00ed, aun as\u00ed, te llegara un art\u00edculo err\u00f3neo, ponte en contacto con nosotros lo antes posible para solucionarlo. Antes de abrir el producto, verifica que el embalaje coincide con el solicitado: color, medida, acabado, etc.<\/p>\n<p>Por su parte, si los productos recibidos presentan alg\u00fan defecto o deterioro, responderemos a las faltas de conformidad seg\u00fan lo expuesto en el apartado \u201cGarant\u00edas\u201d dentro de estas condiciones de venta.<\/p>\n<p>Cuando el producto se haya da\u00f1ado durante el transporte es necesario que nos lo comuniques y que, si es posible, anotes la incidencia en el albar\u00e1n de entrega del transportista. \u00a0<\/p>\n<p>Los productos deben ser devueltos de forma que est\u00e9n protegidos, incluy\u00e9ndolos dentro de una caja o bolsa protectora. \u201cAdvanced Seeds\u201d pone a disposici\u00f3n del comprador una empresa de transporte para la retirada de la mercanc\u00eda, <u>de manera totalmente gratuita<\/u>. Si deseas devolver la mercanc\u00eda con una empresa de transporte distinta de la propuesta por \u201cAdvanced Seeds\u201d, y la empresa de transporte seleccionada ofrece tarifas superiores, deber\u00e1s asumir la diferencia del coste de transporte.<\/p>\n<ol>\n<li><strong><u> Desistimiento:<\/u><\/strong><\/li>\n<\/ol>\n<p>No queremos que te quedes con nada que no te guste, por eso puedes devolver un art\u00edculo si no se ajusta a tus expectativas. Por ello, de acuerdo a lo establecido en la LGDCU, y siempre que seas un comprador de un art\u00edculo para uso particular, dispones del Derecho de Desistimiento, en virtud del cual podr\u00e1s devolver el producto, siempre que \u00e9ste no sea un producto digital del que se haya iniciado la descarga.<\/p>\n<p>El ejercicio de este derecho de desistimiento tendr\u00e1 que realizarse en un <u>plazo m\u00e1ximo de CATORCE (14) d\u00edas<\/u> naturales a partir de su recepci\u00f3n, notific\u00e1ndonos tu decisi\u00f3n de desistir de la compra efectuada (podr\u00e1s utilizar para ello el siguiente modelo de formulario de desistimiento, si lo deseas). [ADJUNTAR MODELO DE DESISTIMIENTO QUE HAY AL FINAL DE ESTE DOCUMENTO]\n<p>Para poder ejercer este derecho, el producto deber\u00e1 encontrarse en perfectas condiciones, y preferiblemente conservar el embalaje original, as\u00ed como todas las piezas. En caso de que los productos no lleguen en perfectas condiciones, no incluyan todas sus piezas y accesorios, o no conserven su embalaje original, \u201cAdvanced Seeds\u201d se reserva el derecho a abonar una cantidad inferior en la devoluci\u00f3n, circunstancia que te ser\u00e1 notificada.<\/p>\n<p>El reembolso del importe de la compra se efectuar\u00e1 una vez haya sido comprobado el estado de la mercanc\u00eda, a trav\u00e9s del mismo medio de pago utilizado en la compra y, en todo caso, antes de que hayan transcurrido 14 d\u00edas naturales desde la recepci\u00f3n fehaciente de la solicitud de desistimiento, siempre y cuando sea \u201cAdvanced Seeds\u201d quien gestione la recogida del art\u00edculo. En caso de que devuelvas el art\u00edculo a trav\u00e9s de una empresa de transportes de tu elecci\u00f3n, el plazo de 14 d\u00edas comenzar\u00e1 a computar desde que \u201cAdvanced Seeds\u201d tenga conocimiento efectivo del env\u00edo de la mercanc\u00eda o, en su defecto, desde la recepci\u00f3n de la misma.<\/p>\n<p>Los gastos de devoluci\u00f3n derivados del ejercicio del derecho de desistimiento ser\u00e1n por cuenta del comprador.<\/p>\n<ol>\n<li><strong><u> Si a\u00fan no ha recibido el pedido:<\/u><\/strong><\/li>\n<\/ol>\n<p>Si todav\u00eda no has recibido el pedido y deseas cancelarlo o modificarlo, solo tienes que informarnos de los cambios que quieres realizar, sin que esto suponga ning\u00fan coste en caso de que tu pedido a\u00fan no haya sido tramitado.<\/p>\n<p><em>Contacto Para Devoluciones:<\/em><\/p>\n<p>*Tel\u00e9fono: 968 629 309<br \/>*Notificaci\u00f3n a trav\u00e9s de esta web en la secci\u00f3n \u00abContacto\u00bb<br \/>*Email: info@advancedseeds.com<\/p>\n<p>Todas las devoluciones de productos deber\u00e1n dirigirse a la siguiente direcci\u00f3n: C\/ Nicolas Ortega Pagan, 5 bajo, 30003, Murcia<\/p>\n<h2>Garant\u00edas<\/h2>\n<p>Excepto aquellos que, por su naturaleza, quedan excluidos de la normativa de garant\u00edas de bienes de consumo, y siempre que el comprador haga un uso particular, todos nuestros productos est\u00e1n garantizados a nivel nacional, frente a <strong>defectos de fabricaci\u00f3n<\/strong> durante <u>dos a\u00f1os<\/u> a partir de la fecha de la compra (o fecha de entrega, si \u00e9sta es posterior), o de un a\u00f1o en caso de que el art\u00edculo no sea nuevo.<\/p>\n<p>Responderemos de las faltas de conformidad, de las que el comprador deber\u00e1 informarnos en el plazo de dos meses desde que tuvo conocimiento de ella.<\/p>\n<p>Si el defecto o la falta de conformidad surge en los primeros 6 meses desde la entrega del art\u00edculo, tanto si se trata de un producto nuevo, como de segunda mano, se presume que el defecto o falta de conformidad ya exist\u00eda cuando el producto fue facturado (o entregado, si es en un momento posterior), es decir, que existe un defecto de origen o de f\u00e1brica del producto, salvo que podamos demostrar que el defecto o falta de conformidad no es de origen sino que se debe, por ejemplo, a un mal uso o mantenimiento dado por el comprador.<\/p>\n<p>Por su parte, si el defecto o la falta de conformidad surge a partir de los 6 primeros meses y hasta los 2 a\u00f1os, la presunci\u00f3n de que el defecto viene de f\u00e1brica no existe.<\/p>\n<p>En caso de producto defectuoso, podremos proceder, seg\u00fan corresponda, a la reparaci\u00f3n, sustituci\u00f3n, rebaja del precio o resoluci\u00f3n del contrato, gestiones que ser\u00e1n totalmente gratuitas para el comprador (incluyendo los gastos de transporte, de existir).<\/p>\n<p>Quedan, por tanto, excluidos de la garant\u00eda los defectos y deterioros producidos por hechos externos, accidentes, utilizaci\u00f3n no conforme a nuestras instrucciones o a las del fabricante (uso incorrecto) o al desgaste habitual. Tambi\u00e9n, los productos modificados o reparados por el cliente o cualquier otra persona no autorizada por \u201cAdvanced Seeds\u201d, as\u00ed como los productos que son objeto de un contrato de espec\u00edfico. En esos casos el consumidor deber\u00e1 hacerse cargo de su reparaci\u00f3n.<\/p>\n<p>Por normativa, y salvo prueba en contrario, se entender\u00e1 que los productos son conformes con el contrato siempre que cumplan todos los requisitos que se expresan a continuaci\u00f3n:<\/p>\n<ol>\n<li>a) Se ajusten a la descripci\u00f3n realizada y posean las cualidades del producto que hayamos presentado al consumidor y usuario en forma de muestra o modelo.<\/li>\n<li>b) Sean aptos para los usos a que ordinariamente se destinen productos similares.<\/li>\n<li>c) Presenten la calidad y prestaciones habituales de un producto del mismo tipo que el consumidor y usuario pueda fundadamente esperar, habida cuenta de la naturaleza del producto.<\/li>\n<\/ol>\n<h2><strong>Resoluci\u00f3n de conflictos<\/strong><\/h2>\n<p>Como as\u00ed la exige la nueva normativa europea, informamos a los usuarios de la existencia de una plataforma europea de resoluci\u00f3n de litigios para contrataciones online. As\u00ed, para la resoluci\u00f3n de litigios en materia de consumo (conforme al Art. 14.1 del Reglamento (UE) 524\/2013), la Comisi\u00f3n Europea facilita una plataforma de resoluci\u00f3n de litigios en l\u00ednea.<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p><strong><u>MODELO DE FORMULARIO DE DESISTIMIENTO<\/u><\/strong><\/p>\n<p>\u00a0<\/p>\n<p>Si, como consumidor y usuario, deseas ejercer tu derecho de desistimiento, puedes hacerlo mediante el presente formulario, que deber\u00e1s rellenar y hacernos llegar.<\/p>\n<p>A la atenci\u00f3n de Garden Seeds Trading, S.L., con domicilio en C\/ Villanueva del R\u00edo Segura, nave 5. P.I. La Polvorista, 30500, Murcia, tel\u00e9fono 968 629 309 y direcci\u00f3n de email info@advancedseeds.com.<\/p>\n<p>Por la presente, comunico que desisto de mi contrato de venta del siguiente producto o relaci\u00f3n de productos:<\/p>\n<p>(Indicar relaci\u00f3n de productos respecto de los cuales se va a ejercitar el derecho de desistimiento)<\/p>\n<p>Pedido el: (Indicar fecha)<\/p>\n<p>Nombre del consumidor y usuario: (Indicar)<\/p>\n<p>Domicilio del consumidor y usuario: (Indicar)<\/p>\n<p>N\u00famero de pedido: (Indicar)<\/p>\n<p>\u00a0<\/p>\n<div class=\"is-divider divider clearfix\" ><\/div>\n\n<div class=\"is-divider divider clearfix\" ><\/div>\n\n<div class=\"is-divider divider clearfix\" ><\/div>\n\n<div class=\"is-divider divider clearfix\" ><\/div>\n\n<div class=\"is-divider divider clearfix\" ><\/div>\n\n<div class=\"is-divider divider clearfix\" ><\/div>\n\n<div class=\"is-divider divider clearfix\" ><\/div>\n\n<div class=\"is-divider divider clearfix\" ><\/div>\n\n<div class=\"is-divider divider clearfix\" ><\/div>\n\n<div class=\"is-divider divider clearfix\" ><\/div>\n\n<div class=\"is-divider divider clearfix\" ><\/div>\n\n<div class=\"is-divider divider clearfix\" ><\/div>\n\n<div class=\"is-divider divider clearfix\" ><\/div>\n\n<div class=\"is-divider divider clearfix\" ><\/div>\n\n<p>_<\/p>\n<p>Firma del consumidor y usuario (solo si el presente formulario se presenta en papel)<\/p>\n<p>Fecha:<\/p>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_118919815 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(0,0,0);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":532,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2208","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.3 (Yoast SEO v26.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Condiciones de Venta y Contrataci\u00f3n - Advanced Seeds<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/advancedseeds.com\/en\/condiciones-de-venta-y-contratacion\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Condiciones de Venta y Contrataci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/advancedseeds.com\/en\/condiciones-de-venta-y-contratacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Advanced Seeds\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-25T11:32:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/advancedseeds.com\/condiciones-de-venta-y-contratacion\/\",\"url\":\"https:\/\/advancedseeds.com\/condiciones-de-venta-y-contratacion\/\",\"name\":\"Condiciones de Venta y Contrataci\u00f3n - Advanced Seeds\",\"isPartOf\":{\"@id\":\"https:\/\/advancedseeds.com\/#website\"},\"datePublished\":\"2021-06-14T16:55:16+00:00\",\"dateModified\":\"2025-11-25T11:32:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/advancedseeds.com\/condiciones-de-venta-y-contratacion\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/advancedseeds.com\/condiciones-de-venta-y-contratacion\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/advancedseeds.com\/condiciones-de-venta-y-contratacion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/advancedseeds.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Condiciones de Venta y Contrataci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/advancedseeds.com\/#website\",\"url\":\"https:\/\/advancedseeds.com\/\",\"name\":\"Advanced Seeds\",\"description\":\"Gen\u00e9ticas Avanzadas en semillas feminizadas y autom\u00e1ticas.\",\"publisher\":{\"@id\":\"https:\/\/advancedseeds.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/advancedseeds.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/advancedseeds.com\/#organization\",\"name\":\"Advanced Seeds\",\"url\":\"https:\/\/advancedseeds.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/advancedseeds.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/advancedseeds.com\/web\/wp-content\/uploads\/2021\/01\/logo-advanced.jpg\",\"contentUrl\":\"https:\/\/advancedseeds.com\/web\/wp-content\/uploads\/2021\/01\/logo-advanced.jpg\",\"width\":600,\"height\":600,\"caption\":\"Advanced Seeds\"},\"image\":{\"@id\":\"https:\/\/advancedseeds.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Condiciones de Venta y Contrataci\u00f3n - Advanced Seeds","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/advancedseeds.com\/en\/condiciones-de-venta-y-contratacion\/","og_locale":"en_GB","og_type":"article","og_title":"Condiciones de Venta y Contrataci\u00f3n","og_url":"https:\/\/advancedseeds.com\/en\/condiciones-de-venta-y-contratacion\/","og_site_name":"Advanced Seeds","article_modified_time":"2025-11-25T11:32:19+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/advancedseeds.com\/condiciones-de-venta-y-contratacion\/","url":"https:\/\/advancedseeds.com\/condiciones-de-venta-y-contratacion\/","name":"Condiciones de Venta y Contrataci\u00f3n - Advanced Seeds","isPartOf":{"@id":"https:\/\/advancedseeds.com\/#website"},"datePublished":"2021-06-14T16:55:16+00:00","dateModified":"2025-11-25T11:32:19+00:00","breadcrumb":{"@id":"https:\/\/advancedseeds.com\/condiciones-de-venta-y-contratacion\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/advancedseeds.com\/condiciones-de-venta-y-contratacion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/advancedseeds.com\/condiciones-de-venta-y-contratacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/advancedseeds.com\/"},{"@type":"ListItem","position":2,"name":"Condiciones de Venta y Contrataci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/advancedseeds.com\/#website","url":"https:\/\/advancedseeds.com\/","name":"Advanced Seeds","description":"Advanced genetics in feminised and automatic seeds.","publisher":{"@id":"https:\/\/advancedseeds.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/advancedseeds.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/advancedseeds.com\/#organization","name":"Advanced Seeds","url":"https:\/\/advancedseeds.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/advancedseeds.com\/#\/schema\/logo\/image\/","url":"https:\/\/advancedseeds.com\/web\/wp-content\/uploads\/2021\/01\/logo-advanced.jpg","contentUrl":"https:\/\/advancedseeds.com\/web\/wp-content\/uploads\/2021\/01\/logo-advanced.jpg","width":600,"height":600,"caption":"Advanced Seeds"},"image":{"@id":"https:\/\/advancedseeds.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/advancedseeds.com\/en\/wp-json\/wp\/v2\/pages\/2208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/advancedseeds.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/advancedseeds.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/advancedseeds.com\/en\/wp-json\/wp\/v2\/users\/532"}],"replies":[{"embeddable":true,"href":"https:\/\/advancedseeds.com\/en\/wp-json\/wp\/v2\/comments?post=2208"}],"version-history":[{"count":6,"href":"https:\/\/advancedseeds.com\/en\/wp-json\/wp\/v2\/pages\/2208\/revisions"}],"predecessor-version":[{"id":29088,"href":"https:\/\/advancedseeds.com\/en\/wp-json\/wp\/v2\/pages\/2208\/revisions\/29088"}],"wp:attachment":[{"href":"https:\/\/advancedseeds.com\/en\/wp-json\/wp\/v2\/media?parent=2208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}